{"id":709,"count":1,"description":"","link":"https:\/\/declix.io\/blog\/tag\/welche-videokonferenz-nutzen","name":"welche Videokonferenz nutzen","slug":"welche-videokonferenz-nutzen","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>welche Videokonferenz nutzen | Declix<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"welche Videokonferenz nutzen | Declix\" \/>\n<meta property=\"og:url\" content=\"https:\/\/declix.io\/blog\/tag\/welche-videokonferenz-nutzen\" \/>\n<meta property=\"og:site_name\" content=\"Declix\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@declix_CH\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/declix.io\\\/blog\\\/tag\\\/welche-videokonferenz-nutzen\",\"url\":\"https:\\\/\\\/declix.io\\\/blog\\\/tag\\\/welche-videokonferenz-nutzen\",\"name\":\"welche Videokonferenz nutzen | Declix\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/declix.io\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/declix.io\\\/blog\\\/tag\\\/welche-videokonferenz-nutzen#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/declix.io\\\/blog\\\/tag\\\/welche-videokonferenz-nutzen#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/declix.io\\\/blog\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"welche Videokonferenz nutzen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/declix.io\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/declix.io\\\/blog\\\/\",\"name\":\"Declix\",\"description\":\"Live Support, Customer service &amp; Online Assistant\",\"publisher\":{\"@id\":\"https:\\\/\\\/declix.io\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/declix.io\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/declix.io\\\/blog\\\/#organization\",\"name\":\"Declix\",\"url\":\"https:\\\/\\\/declix.io\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/declix.io\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/declix.io\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/DeClix-Horizontal-1.png\",\"contentUrl\":\"https:\\\/\\\/declix.io\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/DeClix-Horizontal-1.png\",\"width\":1081,\"height\":283,\"caption\":\"Declix\"},\"image\":{\"@id\":\"https:\\\/\\\/declix.io\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Declix.ch\\\/\",\"https:\\\/\\\/x.com\\\/declix_CH\",\"https:\\\/\\\/www.instagram.com\\\/declix_ch\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/declix7\\\/\",\"https:\\\/\\\/www.pinterest.ch\\\/Declix_CH\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCh-eD053S-x2XbHAYJsywuQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"welche Videokonferenz nutzen | Declix","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_GB","og_type":"article","og_title":"welche Videokonferenz nutzen | Declix","og_url":"https:\/\/declix.io\/blog\/tag\/welche-videokonferenz-nutzen","og_site_name":"Declix","twitter_card":"summary_large_image","twitter_site":"@declix_CH","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/declix.io\/blog\/tag\/welche-videokonferenz-nutzen","url":"https:\/\/declix.io\/blog\/tag\/welche-videokonferenz-nutzen","name":"welche Videokonferenz nutzen | Declix","isPartOf":{"@id":"https:\/\/declix.io\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/declix.io\/blog\/tag\/welche-videokonferenz-nutzen#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/declix.io\/blog\/tag\/welche-videokonferenz-nutzen#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/declix.io\/blog\/en\/"},{"@type":"ListItem","position":2,"name":"welche Videokonferenz nutzen"}]},{"@type":"WebSite","@id":"https:\/\/declix.io\/blog\/#website","url":"https:\/\/declix.io\/blog\/","name":"Declix","description":"Live Support, Customer service &amp; Online Assistant","publisher":{"@id":"https:\/\/declix.io\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/declix.io\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/declix.io\/blog\/#organization","name":"Declix","url":"https:\/\/declix.io\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/declix.io\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/declix.io\/blog\/wp-content\/uploads\/2021\/01\/DeClix-Horizontal-1.png","contentUrl":"https:\/\/declix.io\/blog\/wp-content\/uploads\/2021\/01\/DeClix-Horizontal-1.png","width":1081,"height":283,"caption":"Declix"},"image":{"@id":"https:\/\/declix.io\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Declix.ch\/","https:\/\/x.com\/declix_CH","https:\/\/www.instagram.com\/declix_ch\/","https:\/\/www.linkedin.com\/company\/declix7\/","https:\/\/www.pinterest.ch\/Declix_CH","https:\/\/www.youtube.com\/channel\/UCh-eD053S-x2XbHAYJsywuQ"]}]}},"_links":{"self":[{"href":"https:\/\/declix.io\/blog\/wp-json\/wp\/v2\/tags\/709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/declix.io\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/declix.io\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/declix.io\/blog\/wp-json\/wp\/v2\/posts?tags=709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}